{"id":15152,"date":"2022-08-30T15:24:09","date_gmt":"2022-08-30T18:24:09","guid":{"rendered":"https:\/\/www.colescba.org.ar\/portal\/?p=15152"},"modified":"2022-08-30T15:24:10","modified_gmt":"2022-08-30T18:24:10","slug":"reunion-con-las-nuevas-autoridades-del-registro-de-la-propiedad","status":"publish","type":"post","link":"https:\/\/www.colescba.org.ar\/portal\/novedades\/reunion-con-las-nuevas-autoridades-del-registro-de-la-propiedad-30-08-2022","title":{"rendered":"Reuni\u00f3n con las nuevas autoridades del Registro\u00a0de la Propiedad"},"content":{"rendered":"\n<p>Con el objetivo de continuar fortaleciendo los v\u00ednculos con los organismos del Estado y avanzar en el tratamiento de temas de inter\u00e9s para el notariado, se realiz\u00f3 una reuni\u00f3n de trabajo de la que participaron las nuevas autoridades del Registro de la Propiedad Inmueble de la Provincia de Buenos Aires junto a miembros del Comit\u00e9 Ejecutivo del Colegio de Escribanos bonaerense.<\/p>\n\n\n\n<p>El encuentro, que tuvo lugar el martes 30 de agosto, en la sede del Ministerio de Hacienda y Finanzas de la Provincia de Buenos Aires, estuvo encabezado por la Dra. Anal\u00eda Tello, Subsecretaria T\u00e9cnica, Administrativa y Legal del mencionado Ministerio; acompa\u00f1ada por el recientemente designado Director Provincial del Registro de la Propiedad, Dr. Jos\u00e9 Horacio Comas; y la Dra. Mar\u00eda Eugenia Arrieta, Directora de Servicios Registrales del organismo.<\/p>\n\n\n\n<p>Participaron por parte del Colegio de Escribanos bonaerense, el Presidente, Diego Molina; la Vicepresidente Primera, Alicia Broccardo; la Secretaria de Gobierno, Karen Weiss; y la Secretaria de Relaciones Institucionales, Carina P\u00e9rez Lozano.<\/p>\n\n\n\n<p>Como ya se dijo, durante la reuni\u00f3n se dio tratamiento en conjunto a temas de importancia para la labor notarial, en tanto que las autoridades del Colegio valoraron la misma como altamente positiva, manifestando la trascendencia de afianzar los v\u00ednculos ya existentes para lograr avances concretos que redunden en la optimizaci\u00f3n del trabajo de los escribanos y en beneficios para la ciudadan\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el objetivo de continuar fortaleciendo los v\u00ednculos con los organismos del Estado y avanzar en el tratamiento de temas de inter\u00e9s para el notariado, se realiz\u00f3 una reuni\u00f3n de trabajo de la que participaron las nuevas autoridades del Registro de la Propiedad Inmueble de la Provincia de Buenos Aires junto a miembros del Comit\u00e9 [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":15153,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"noticias":[],"class_list":["post-15152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.colescba.org.ar\/portal\/wp-json\/wp\/v2\/posts\/15152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.colescba.org.ar\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.colescba.org.ar\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.colescba.org.ar\/portal\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.colescba.org.ar\/portal\/wp-json\/wp\/v2\/comments?post=15152"}],"version-history":[{"count":2,"href":"https:\/\/www.colescba.org.ar\/portal\/wp-json\/wp\/v2\/posts\/15152\/revisions"}],"predecessor-version":[{"id":15155,"href":"https:\/\/www.colescba.org.ar\/portal\/wp-json\/wp\/v2\/posts\/15152\/revisions\/15155"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.colescba.org.ar\/portal\/wp-json\/wp\/v2\/media\/15153"}],"wp:attachment":[{"href":"https:\/\/www.colescba.org.ar\/portal\/wp-json\/wp\/v2\/media?parent=15152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.colescba.org.ar\/portal\/wp-json\/wp\/v2\/categories?post=15152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.colescba.org.ar\/portal\/wp-json\/wp\/v2\/tags?post=15152"},{"taxonomy":"noticias","embeddable":true,"href":"https:\/\/www.colescba.org.ar\/portal\/wp-json\/wp\/v2\/noticias?post=15152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}