{"id":15211,"date":"2022-09-01T09:13:55","date_gmt":"2022-09-01T12:13:55","guid":{"rendered":"https:\/\/www.colescba.org.ar\/portal\/?p=15211"},"modified":"2022-10-25T14:07:47","modified_gmt":"2022-10-25T17:07:47","slug":"bernardo-casagrande-quinteto","status":"publish","type":"post","link":"https:\/\/www.colescba.org.ar\/portal\/agenda-archivo\/bernardo-casagrande-quinteto-01-09-2022","title":{"rendered":"Bernardo Casagrande Quinteto"},"content":{"rendered":"\n<p>Andr\u00e9s Mart\u00ednez (piano) \/ Juan Ignacio Puente (guitarra)<br>Valentino Sampaoli (bajo)\/ Agust\u00edn C\u00e1ceres (bater\u00eda)<br>Bernardo Casagrande (saxo tenor, composiciones y arreglos).<\/p>\n\n\n\n<p>Se solicitan alimentos no perecederos para ser entregados al Hogar de Ancianos Dardo Rocha de la ciudad de La Plata<\/p>\n\n\n\n<p>23 de septiembre de 2022 &#8211; 20 hs.<br>LUGAR: Sal\u00f3n de actos del Colegio<br>Avda. 13 N\u00ba 770 &#8211; La Plata<\/p>\n\n\n\n<p>Entrada libre y gratuita <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Andr\u00e9s Mart\u00ednez (piano) \/ Juan Ignacio Puente (guitarra)Valentino Sampaoli (bajo)\/ Agust\u00edn C\u00e1ceres (bater\u00eda)Bernardo Casagrande (saxo tenor, composiciones y arreglos). Se solicitan alimentos no perecederos para ser entregados al Hogar de Ancianos Dardo Rocha de la ciudad de La Plata 23 de septiembre de 2022 &#8211; 20 hs.LUGAR: Sal\u00f3n de actos del ColegioAvda. 13 N\u00ba 770 [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":15212,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[100],"tags":[],"noticias":[],"class_list":["post-15211","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agenda-archivo"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.colescba.org.ar\/portal\/wp-json\/wp\/v2\/posts\/15211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.colescba.org.ar\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.colescba.org.ar\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.colescba.org.ar\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.colescba.org.ar\/portal\/wp-json\/wp\/v2\/comments?post=15211"}],"version-history":[{"count":2,"href":"https:\/\/www.colescba.org.ar\/portal\/wp-json\/wp\/v2\/posts\/15211\/revisions"}],"predecessor-version":[{"id":15214,"href":"https:\/\/www.colescba.org.ar\/portal\/wp-json\/wp\/v2\/posts\/15211\/revisions\/15214"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.colescba.org.ar\/portal\/wp-json\/wp\/v2\/media\/15212"}],"wp:attachment":[{"href":"https:\/\/www.colescba.org.ar\/portal\/wp-json\/wp\/v2\/media?parent=15211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.colescba.org.ar\/portal\/wp-json\/wp\/v2\/categories?post=15211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.colescba.org.ar\/portal\/wp-json\/wp\/v2\/tags?post=15211"},{"taxonomy":"noticias","embeddable":true,"href":"https:\/\/www.colescba.org.ar\/portal\/wp-json\/wp\/v2\/noticias?post=15211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}